{"id":6600,"date":"2022-04-25T09:55:06","date_gmt":"2022-04-25T07:55:06","guid":{"rendered":"https:\/\/laterale-residences.com\/rio-knepfelfacht\/"},"modified":"2023-03-12T07:48:48","modified_gmt":"2023-03-12T06:48:48","slug":"rio-knepfelfacht","status":"publish","type":"post","link":"https:\/\/laterale-residences.com\/pt-pt\/rio-knepfelfacht\/","title":{"rendered":"Knepfelfacht"},"content":{"rendered":"<p><strong>Riquewihr \u2013 s\u00e1bado 10 de Junho \u2013 domingo 11 de Junho de 2023<\/strong><\/p>\n<p>Todos os anos, no segundo fim-de-semana de junho, Riquewihr presta homenagem a um dos pratos mais emblem\u00e1ticos da Als\u00e1cia e do universo do Reno: Knepfel (podemos traduzir-se como \u201cquenelle\u201d). Knepfle \u00e9 conhecida desde a Idade M\u00e9dia. As varia\u00e7\u00f5es das receitas s\u00e3o infinitas e todos os anos, os chefs criam novas! Sublimado em modo terroir, com queijo fresco, alho de ursos, croutons e bacon ou Munster fumado com batatas fritas de bacon camponeses, mas tamb\u00e9m ensolarado com Brocciu Storzapretti e coulis de tomate, ou vegetal com espinafres, pistou, parmes\u00e3o e tomate. Esta \u00e9 uma oportunidade para fazer as gourmands durante este fim de semana.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-14350 size-full\" src=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_141455042_iOS-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_141455042_iOS-scaled.jpg 2560w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_141455042_iOS-300x225.jpg 300w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_141455042_iOS-1024x768.jpg 1024w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_141455042_iOS-768x576.jpg 768w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_141455042_iOS-1536x1152.jpg 1536w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_141455042_iOS-2048x1536.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\"><\/p>\n<p>O grande evento do fim de semana \u00e9 a competi\u00e7\u00e3o de culin\u00e1ria da \u201cmelhor knepfa\u201d organizada por Nicolas Rieffel, onde os chefs da regi\u00e3o competem amigavelmente. Suas receitas ser\u00e3o provadas por um j\u00fari eminente, presidido por Marc Haeberlin.<\/p>\n<p>O concurso ter\u00e1 lugar no <strong>s\u00e1bado 10 de Junho de 2023, das 15h \u00e0s 17h<\/strong>, na Place de l\u2019H\u00f4tel de Ville em Riquewihr, com chefs da regi\u00e3o no j\u00fari.<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-14330\" src=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_141132032_iOS-300x225.jpg\" alt=\"\" width=\"381\" height=\"286\" srcset=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_141132032_iOS-300x225.jpg 300w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_141132032_iOS-1024x768.jpg 1024w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_141132032_iOS-768x576.jpg 768w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_141132032_iOS-1536x1152.jpg 1536w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_141132032_iOS-2048x1536.jpg 2048w\" sizes=\"(max-width: 381px) 100vw, 381px\"> <img decoding=\"async\" class=\"alignnone wp-image-14320\" src=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_141032979_iOS-300x225.jpg\" alt=\"\" width=\"381\" height=\"286\" srcset=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_141032979_iOS-300x225.jpg 300w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_141032979_iOS-1024x768.jpg 1024w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_141032979_iOS-768x576.jpg 768w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_141032979_iOS-1536x1152.jpg 1536w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_141032979_iOS-2048x1536.jpg 2048w\" sizes=\"(max-width: 381px) 100vw, 381px\"><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-14300 size-full\" src=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_140848052_iOS-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_140848052_iOS-scaled.jpg 2560w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_140848052_iOS-300x225.jpg 300w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_140848052_iOS-1024x768.jpg 1024w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_140848052_iOS-768x576.jpg 768w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_140848052_iOS-1536x1152.jpg 1536w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_140848052_iOS-2048x1536.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\"><\/p>\n<p>O princ\u00edpio \u00e9 simples: cozinhe uma receita inovadora e criativa para este prato tradicional alsaciano. Os candidatos v\u00e3o representar restaurantes na regi\u00e3o, cada um apresentar\u00e1 a sua receita, bem como o t\u00edtulo com uma breve descri\u00e7\u00e3o. A competi\u00e7\u00e3o come\u00e7a depois de 10 de maio e o comit\u00e9 escolher\u00e1 4 finalistas. Ser\u00e3o informados por e-mail e devem enviar antes de 20 de maio de 2022 a sua receita escrita para 4 pessoas. A receita vencedora do concurso ser\u00e1 escolhida no mesmo dia e publicada na comunica\u00e7\u00e3o social.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-14360\" src=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_143754881_iOS-225x300.jpg\" alt=\"\" width=\"383\" height=\"511\" srcset=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_143754881_iOS-225x300.jpg 225w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_143754881_iOS-768x1024.jpg 768w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_143754881_iOS-1152x1536.jpg 1152w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_143754881_iOS-1536x2048.jpg 1536w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_143754881_iOS-scaled.jpg 1920w\" sizes=\"(max-width: 383px) 100vw, 383px\">  <img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-14340\" src=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_141418821_iOS-225x300.jpg\" alt=\"\" width=\"384\" height=\"512\" srcset=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_141418821_iOS-225x300.jpg 225w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_141418821_iOS-768x1024.jpg 768w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_141418821_iOS-1152x1536.jpg 1152w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_141418821_iOS-1536x2048.jpg 1536w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/20220611_141418821_iOS-scaled.jpg 1920w\" sizes=\"(max-width: 384px) 100vw, 384px\"><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1093 size-full\" src=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/KnepfelFescht-Riquewihr-02-scaled.jpg\" alt=\"Laterale Residences Riquewihr Knepfelfacht 02\" width=\"2560\" height=\"1707\" srcset=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/KnepfelFescht-Riquewihr-02-scaled.jpg 2560w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/KnepfelFescht-Riquewihr-02-300x200.jpg 300w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/KnepfelFescht-Riquewihr-02-1024x683.jpg 1024w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/KnepfelFescht-Riquewihr-02-768x512.jpg 768w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/KnepfelFescht-Riquewihr-02-1536x1024.jpg 1536w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/KnepfelFescht-Riquewihr-02-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\"><\/p>\n<p><iframe title=\"Laterale Residences Riquewihr Knepfelfacht\" src=\"https:\/\/player.vimeo.com\/video\/719571949?h=4eb0c01da4&amp;dnt=1&amp;app_id=122963\" width=\"800\" height=\"450\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-14547 size-full\" src=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/Laterale-Residences-Riquewihr-Knepfelfacht-a-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/Laterale-Residences-Riquewihr-Knepfelfacht-a-scaled.jpg 2560w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/Laterale-Residences-Riquewihr-Knepfelfacht-a-300x225.jpg 300w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/Laterale-Residences-Riquewihr-Knepfelfacht-a-1024x768.jpg 1024w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/Laterale-Residences-Riquewihr-Knepfelfacht-a-768x576.jpg 768w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/Laterale-Residences-Riquewihr-Knepfelfacht-a-1536x1152.jpg 1536w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/Laterale-Residences-Riquewihr-Knepfelfacht-a-2048x1536.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\"><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-14537 size-full\" src=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/Laterale-Residences-Riquewihr-Knepfelfacht-j-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1611\" srcset=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/Laterale-Residences-Riquewihr-Knepfelfacht-j-scaled.jpg 2560w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/Laterale-Residences-Riquewihr-Knepfelfacht-j-300x189.jpg 300w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/Laterale-Residences-Riquewihr-Knepfelfacht-j-1024x644.jpg 1024w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/Laterale-Residences-Riquewihr-Knepfelfacht-j-768x483.jpg 768w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/Laterale-Residences-Riquewihr-Knepfelfacht-j-1536x967.jpg 1536w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/06\/Laterale-Residences-Riquewihr-Knepfelfacht-j-2048x1289.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Riquewihr &#8211; s\u00e1bado 10 de Junho &#8211; domingo 11 de Junho de 2023<br \/>\nProve os diferentes pratos oferecidos com base no Knepfle e delicie as suas papilas gustativas para um fim de semana! V\u00e1rias atividades s\u00e3o organizadas para colocar este prato t\u00edpico em destaque: degusta\u00e7\u00e3o, venda, concurso do melhor Knepfel ..<\/p>\n","protected":false},"author":1,"featured_media":1987,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[77],"tags":[],"class_list":["post-6600","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.7 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Knepfelfacht - Laterale Residences<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/laterale-residences.com\/pt-pt\/rio-knepfelfacht\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Knepfelfacht\" \/>\n<meta property=\"og:description\" content=\"Riquewihr - s\u00e1bado 10 de Junho - domingo 11 de Junho de 2023 Prove os diferentes pratos oferecidos com base no Knepfle e delicie as suas papilas gustativas para um fim de semana! V\u00e1rias atividades s\u00e3o organizadas para colocar este prato t\u00edpico em destaque: degusta\u00e7\u00e3o, venda, concurso do melhor Knepfel ..\" \/>\n<meta property=\"og:url\" content=\"https:\/\/laterale-residences.com\/pt-pt\/rio-knepfelfacht\/\" \/>\n<meta property=\"og:site_name\" content=\"Laterale Residences\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-25T07:55:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-12T06:48:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/riquewihr-knepfelfacht-2018f-1140x530-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1140\" \/>\n\t<meta property=\"og:image:height\" content=\"530\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"contact@laterale-residences.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"contact@laterale-residences.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/pt-pt\\\/rio-knepfelfacht\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/pt-pt\\\/rio-knepfelfacht\\\/\"},\"author\":{\"name\":\"contact@laterale-residences.com\",\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/e059e7fbfe09a1de4a5070385ec9fce4\"},\"headline\":\"Knepfelfacht\",\"datePublished\":\"2022-04-25T07:55:06+00:00\",\"dateModified\":\"2023-03-12T06:48:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/pt-pt\\\/rio-knepfelfacht\\\/\"},\"wordCount\":288,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/pt-pt\\\/rio-knepfelfacht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/laterale-residences.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/riquewihr-knepfelfacht-2018f-1140x530-1.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/laterale-residences.com\\\/pt-pt\\\/rio-knepfelfacht\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/pt-pt\\\/rio-knepfelfacht\\\/\",\"url\":\"https:\\\/\\\/laterale-residences.com\\\/pt-pt\\\/rio-knepfelfacht\\\/\",\"name\":\"Knepfelfacht - Laterale Residences\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/pt-pt\\\/rio-knepfelfacht\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/pt-pt\\\/rio-knepfelfacht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/laterale-residences.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/riquewihr-knepfelfacht-2018f-1140x530-1.jpg\",\"datePublished\":\"2022-04-25T07:55:06+00:00\",\"dateModified\":\"2023-03-12T06:48:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/pt-pt\\\/rio-knepfelfacht\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/laterale-residences.com\\\/pt-pt\\\/rio-knepfelfacht\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/pt-pt\\\/rio-knepfelfacht\\\/#primaryimage\",\"url\":\"https:\\\/\\\/laterale-residences.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/riquewihr-knepfelfacht-2018f-1140x530-1.jpg\",\"contentUrl\":\"https:\\\/\\\/laterale-residences.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/riquewihr-knepfelfacht-2018f-1140x530-1.jpg\",\"width\":1140,\"height\":530},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/pt-pt\\\/rio-knepfelfacht\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/laterale-residences.com\\\/pt-pt\\\/rececao\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Knepfelfacht\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/laterale-residences.com\\\/pt-pt\\\/\",\"name\":\"Laterale Residences\",\"description\":\"Appartements Vacances Riquewihr sur la route des vins d&#039;Alsace\",\"publisher\":{\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/laterale-residences.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/pt-pt\\\/#organization\",\"name\":\"Laterale Residences\",\"url\":\"https:\\\/\\\/laterale-residences.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/laterale-residences.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo_laterale_residences_etoiles.png\",\"contentUrl\":\"https:\\\/\\\/laterale-residences.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo_laterale_residences_etoiles.png\",\"width\":600,\"height\":600,\"caption\":\"Laterale Residences\"},\"image\":{\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/e059e7fbfe09a1de4a5070385ec9fce4\",\"name\":\"contact@laterale-residences.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2c6c46f89a7f510c694de34f653d75e6ce9a2782a83b3663358d125500655620?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2c6c46f89a7f510c694de34f653d75e6ce9a2782a83b3663358d125500655620?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2c6c46f89a7f510c694de34f653d75e6ce9a2782a83b3663358d125500655620?s=96&d=mm&r=g\",\"caption\":\"contact@laterale-residences.com\"},\"sameAs\":[\"https:\\\/\\\/laterale-residences.com\"],\"worksFor\":\"LATERALE RESIDENCES sarl\",\"url\":\"https:\\\/\\\/laterale-residences.com\\\/pt-pt\\\/author\\\/contactlaterale-residences-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Knepfelfacht - Laterale Residences","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/laterale-residences.com\/pt-pt\/rio-knepfelfacht\/","og_locale":"pt_PT","og_type":"article","og_title":"Knepfelfacht","og_description":"Riquewihr - s\u00e1bado 10 de Junho - domingo 11 de Junho de 2023 Prove os diferentes pratos oferecidos com base no Knepfle e delicie as suas papilas gustativas para um fim de semana! V\u00e1rias atividades s\u00e3o organizadas para colocar este prato t\u00edpico em destaque: degusta\u00e7\u00e3o, venda, concurso do melhor Knepfel ..","og_url":"https:\/\/laterale-residences.com\/pt-pt\/rio-knepfelfacht\/","og_site_name":"Laterale Residences","article_published_time":"2022-04-25T07:55:06+00:00","article_modified_time":"2023-03-12T06:48:48+00:00","og_image":[{"width":1140,"height":530,"url":"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/riquewihr-knepfelfacht-2018f-1140x530-1.jpg","type":"image\/jpeg"}],"author":"contact@laterale-residences.com","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"contact@laterale-residences.com","Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/laterale-residences.com\/pt-pt\/rio-knepfelfacht\/#article","isPartOf":{"@id":"https:\/\/laterale-residences.com\/pt-pt\/rio-knepfelfacht\/"},"author":{"name":"contact@laterale-residences.com","@id":"https:\/\/laterale-residences.com\/pt-pt\/#\/schema\/person\/e059e7fbfe09a1de4a5070385ec9fce4"},"headline":"Knepfelfacht","datePublished":"2022-04-25T07:55:06+00:00","dateModified":"2023-03-12T06:48:48+00:00","mainEntityOfPage":{"@id":"https:\/\/laterale-residences.com\/pt-pt\/rio-knepfelfacht\/"},"wordCount":288,"commentCount":0,"publisher":{"@id":"https:\/\/laterale-residences.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/laterale-residences.com\/pt-pt\/rio-knepfelfacht\/#primaryimage"},"thumbnailUrl":"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/riquewihr-knepfelfacht-2018f-1140x530-1.jpg","articleSection":["Not\u00edcias"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/laterale-residences.com\/pt-pt\/rio-knepfelfacht\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/laterale-residences.com\/pt-pt\/rio-knepfelfacht\/","url":"https:\/\/laterale-residences.com\/pt-pt\/rio-knepfelfacht\/","name":"Knepfelfacht - Laterale Residences","isPartOf":{"@id":"https:\/\/laterale-residences.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/laterale-residences.com\/pt-pt\/rio-knepfelfacht\/#primaryimage"},"image":{"@id":"https:\/\/laterale-residences.com\/pt-pt\/rio-knepfelfacht\/#primaryimage"},"thumbnailUrl":"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/riquewihr-knepfelfacht-2018f-1140x530-1.jpg","datePublished":"2022-04-25T07:55:06+00:00","dateModified":"2023-03-12T06:48:48+00:00","breadcrumb":{"@id":"https:\/\/laterale-residences.com\/pt-pt\/rio-knepfelfacht\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/laterale-residences.com\/pt-pt\/rio-knepfelfacht\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/laterale-residences.com\/pt-pt\/rio-knepfelfacht\/#primaryimage","url":"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/riquewihr-knepfelfacht-2018f-1140x530-1.jpg","contentUrl":"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/riquewihr-knepfelfacht-2018f-1140x530-1.jpg","width":1140,"height":530},{"@type":"BreadcrumbList","@id":"https:\/\/laterale-residences.com\/pt-pt\/rio-knepfelfacht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/laterale-residences.com\/pt-pt\/rececao\/"},{"@type":"ListItem","position":2,"name":"Knepfelfacht"}]},{"@type":"WebSite","@id":"https:\/\/laterale-residences.com\/pt-pt\/#website","url":"https:\/\/laterale-residences.com\/pt-pt\/","name":"Laterale Residences","description":"Appartements Vacances Riquewihr sur la route des vins d&#039;Alsace","publisher":{"@id":"https:\/\/laterale-residences.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/laterale-residences.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/laterale-residences.com\/pt-pt\/#organization","name":"Laterale Residences","url":"https:\/\/laterale-residences.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/laterale-residences.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/laterale-residences.com\/wp-content\/uploads\/2021\/07\/logo_laterale_residences_etoiles.png","contentUrl":"https:\/\/laterale-residences.com\/wp-content\/uploads\/2021\/07\/logo_laterale_residences_etoiles.png","width":600,"height":600,"caption":"Laterale Residences"},"image":{"@id":"https:\/\/laterale-residences.com\/pt-pt\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/laterale-residences.com\/pt-pt\/#\/schema\/person\/e059e7fbfe09a1de4a5070385ec9fce4","name":"contact@laterale-residences.com","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/2c6c46f89a7f510c694de34f653d75e6ce9a2782a83b3663358d125500655620?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2c6c46f89a7f510c694de34f653d75e6ce9a2782a83b3663358d125500655620?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2c6c46f89a7f510c694de34f653d75e6ce9a2782a83b3663358d125500655620?s=96&d=mm&r=g","caption":"contact@laterale-residences.com"},"sameAs":["https:\/\/laterale-residences.com"],"worksFor":"LATERALE RESIDENCES sarl","url":"https:\/\/laterale-residences.com\/pt-pt\/author\/contactlaterale-residences-com\/"}]}},"_links":{"self":[{"href":"https:\/\/laterale-residences.com\/pt-pt\/wp-json\/wp\/v2\/posts\/6600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laterale-residences.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laterale-residences.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laterale-residences.com\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laterale-residences.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=6600"}],"version-history":[{"count":17,"href":"https:\/\/laterale-residences.com\/pt-pt\/wp-json\/wp\/v2\/posts\/6600\/revisions"}],"predecessor-version":[{"id":16932,"href":"https:\/\/laterale-residences.com\/pt-pt\/wp-json\/wp\/v2\/posts\/6600\/revisions\/16932"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laterale-residences.com\/pt-pt\/wp-json\/wp\/v2\/media\/1987"}],"wp:attachment":[{"href":"https:\/\/laterale-residences.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=6600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laterale-residences.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=6600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laterale-residences.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=6600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}