{"id":6780,"date":"2022-04-25T08:26:42","date_gmt":"2022-04-25T06:26:42","guid":{"rendered":"https:\/\/laterale-residences.com\/selestat\/"},"modified":"2022-07-01T09:15:50","modified_gmt":"2022-07-01T07:15:50","slug":"selestat","status":"publish","type":"post","link":"https:\/\/laterale-residences.com\/es\/selestat\/","title":{"rendered":"Selestat"},"content":{"rendered":"<p>Cuenta la leyenda que la ciudad fue fundada por el gigante Sletto. El primer registro escrito data del siglo VIII, pero el sitio era entonces parte del pueblo de Kintzheim. La expansi\u00f3n de la ciudad comenz\u00f3 en el siglo XI, cuando Hildegarde de Buren, madre del primero de los Hohenstaufen, fund\u00f3 all\u00ed una iglesia que fue ocupada a partir de 1094 por monjes de Conques, venerando a Sainte Foy. Este priorato dirige la ciudad hasta que Federico II de Hohenstaufen otorga el estatus de ciudad libre a S\u00e9lestat. Luego, el poder pas\u00f3 gradualmente a la burgues\u00eda. S\u00e9lestat prosper\u00f3, se convirti\u00f3 en miembro de la dec\u00e1polis, ampli\u00f3 sus fortificaciones, recibi\u00f3 \u00f3rdenes mon\u00e1sticas y comerci\u00f3. El Renacimiento marca el per\u00edodo glorioso de la ciudad que se convierte en capital del humanismo. Su escuela se hizo famosa en toda Europa. La Reforma, la Guerra de los Campesinos y la Guerra de los Treinta A\u00f1os marcan el declive de S\u00e9lestat. Despu\u00e9s del Tratado de Westfalia, como el resto de Alsacia, la ciudad pas\u00f3 a ser francesa. Vauban construy\u00f3 nuevas murallas y S\u00e9lestat se convirti\u00f3 en una ciudad de guarnici\u00f3n. La ciudad encontr\u00f3 entonces cierta prosperidad, pero su expansi\u00f3n qued\u00f3 limitada en beneficio de las otras grandes ciudades de Alsacia. Su historia sigue entonces la de la regi\u00f3n.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-8973 size-full\" src=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-en-1500.jpg\" alt=\"\" width=\"1200\" height=\"584\" srcset=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-en-1500.jpg 1200w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-en-1500-300x146.jpg 300w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-en-1500-1024x498.jpg 1024w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-en-1500-768x374.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\"><\/p>\n<p><strong>S\u00e9lestat: la ciudad fortificada alrededor del a\u00f1o 1500 d.C. JC.<\/strong><br>\nReproduction issue du Livre illustr\u00e9 : <strong>Villes fortifi\u00e9es d\u2019Alsace et ch\u00e2teaux de plaine <\/strong>de Guy Trendel (Auteur), Christophe Carmona (Illustrations)<br>\nEditor: <span class=\"a-list-item\">ID Publishing; Edici\u00f3n ilustrada (1 de abril de 2016)<\/span><br>\n<a href=\"https:\/\/www.amazon.fr\/Villes-fortifi%C3%A9es-dAlsace-ch%C3%A2teaux-plaine\/dp\/2367010803\/ref=asc_df_2367010803\/?tag=googshopfr-21&amp;linkCode=df0&amp;hvadid=228565470380&amp;hvpos=&amp;hvnetw=g&amp;hvrand=5364057057137916841&amp;hvpone=&amp;hvptwo=&amp;hvqmt=&amp;hvdev=c&amp;hvdvcmdl=&amp;hvlocint=&amp;hvlocphy=9055991&amp;hvtargid=pla-487873976771&amp;psc=1\" target=\"_blank\" rel=\"noopener\">Compra el libro en Amazon<\/a><\/p>\n<h3>Los inevitables<\/h3>\n<p><strong>La Biblioteca Humanista<\/strong> : ahora se encuentra en una antigua lonja de trigo del siglo XIX. All\u00ed se presenta la biblioteca que perteneci\u00f3 a Beatus Rhenanus, legada a la ciudad, que representa m\u00e1s de 3000 documentos (manuscritos, incunables e impresos) que abarcan un per\u00edodo que va del siglo VII al XVI. Este museo es casi \u00fanico en Europa. La biblioteca ha sido completamente renovada y reabierta en 2019 con una nueva selecci\u00f3n de libros, en un entorno inmejorable.<\/p>\n<p><a href=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-131430918_iOS-scaled.jpg\"><img decoding=\"async\" class=\"aligncenter wp-image-10063 size-full\" src=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-131430918_iOS-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-131430918_iOS-scaled.jpg 2560w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-131430918_iOS-300x225.jpg 300w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-131430918_iOS-1024x768.jpg 1024w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-131430918_iOS-768x576.jpg 768w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-131430918_iOS-1536x1152.jpg 1536w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-131430918_iOS-2048x1536.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\"><\/a><\/p>\n<p><a href=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-131201250_iOS-scaled.jpg\"><img decoding=\"async\" class=\"aligncenter wp-image-10041 size-full\" src=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-131201250_iOS-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-131201250_iOS-scaled.jpg 2560w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-131201250_iOS-300x225.jpg 300w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-131201250_iOS-1024x768.jpg 1024w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-131201250_iOS-768x576.jpg 768w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-131201250_iOS-1536x1152.jpg 1536w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-131201250_iOS-2048x1536.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\"><\/a><\/p>\n<p>Iglesia <strong>de Saint-Georges<\/strong> : Iglesia g\u00f3tica construida entre los siglos XIII y XVI.<\/p>\n<p><a href=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Selestat-Noel-01-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-907 size-full\" src=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Selestat-Noel-01-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Selestat-Noel-01-scaled.jpg 2560w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Selestat-Noel-01-300x225.jpg 300w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Selestat-Noel-01-1024x768.jpg 1024w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Selestat-Noel-01-768x576.jpg 768w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Selestat-Noel-01-1536x1152.jpg 1536w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Selestat-Noel-01-2048x1536.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\"><\/a><br>\n<a href=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Selestat-Noel-02-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-906 size-full\" src=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Selestat-Noel-02-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Selestat-Noel-02-scaled.jpg 2560w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Selestat-Noel-02-300x225.jpg 300w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Selestat-Noel-02-1024x768.jpg 1024w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Selestat-Noel-02-768x576.jpg 768w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Selestat-Noel-02-1536x1152.jpg 1536w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Selestat-Noel-02-2048x1536.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\"><\/a><\/p>\n<p><strong>La Torre de las Brujas<\/strong> : (Plaza De Lattre de Tassigny) form\u00f3 parte del primer recinto de la ciudad de 1216.<\/p>\n<p>Pasee por las calles de S\u00e9lestat para descubrir muchas casas renacentistas, <strong>Place du March\u00e9 aux Choux, rue Dorlan, Quai des Tanneurs, rue de la Porte de Brisach.<\/strong><\/p>\n<p><a href=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-133500850_iOS-scaled-e1651341347929.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10118 size-full\" src=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-133500850_iOS-scaled-e1651341347929.jpg\" alt=\"\" width=\"1920\" height=\"2560\" srcset=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-133500850_iOS-scaled-e1651341347929.jpg 1920w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-133500850_iOS-scaled-e1651341347929-225x300.jpg 225w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-133500850_iOS-scaled-e1651341347929-768x1024.jpg 768w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-133500850_iOS-scaled-e1651341347929-1152x1536.jpg 1152w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-133500850_iOS-scaled-e1651341347929-1536x2048.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\"><\/a><\/p>\n<p><a href=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-133355986_iOS-scaled-e1651341360358.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10107 size-full\" src=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-133355986_iOS-scaled-e1651341360358.jpg\" alt=\"\" width=\"1920\" height=\"2560\" srcset=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-133355986_iOS-scaled-e1651341360358.jpg 1920w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-133355986_iOS-scaled-e1651341360358-225x300.jpg 225w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-133355986_iOS-scaled-e1651341360358-768x1024.jpg 768w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-133355986_iOS-scaled-e1651341360358-1152x1536.jpg 1152w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-133355986_iOS-scaled-e1651341360358-1536x2048.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\"><\/a><\/p>\n<p><a href=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-125025037_iOS-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9942 size-full\" src=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-125025037_iOS-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-125025037_iOS-scaled.jpg 2560w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-125025037_iOS-300x225.jpg 300w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-125025037_iOS-1024x768.jpg 1024w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-125025037_iOS-768x576.jpg 768w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-125025037_iOS-1536x1152.jpg 1536w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-125025037_iOS-2048x1536.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\"><\/a><\/p>\n<p><a href=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-103507137_iOS-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9843 size-full\" src=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-103507137_iOS-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-103507137_iOS-scaled.jpg 2560w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-103507137_iOS-300x225.jpg 300w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-103507137_iOS-1024x768.jpg 1024w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-103507137_iOS-768x576.jpg 768w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-103507137_iOS-1536x1152.jpg 1536w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-103507137_iOS-2048x1536.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\"><\/a><\/p>\n<p><strong>La Torre Nueva<\/strong> : una de las puertas de las antiguas murallas de la ciudad construida en el siglo XIII<\/p>\n<p><a href=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-103200890_iOS-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9777 size-full\" src=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-103200890_iOS-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-103200890_iOS-scaled.jpg 2560w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-103200890_iOS-300x225.jpg 300w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-103200890_iOS-1024x768.jpg 1024w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-103200890_iOS-768x576.jpg 768w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-103200890_iOS-1536x1152.jpg 1536w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-103200890_iOS-2048x1536.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\"><\/a><\/p>\n<p><a href=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-103228449_iOS-scaled-e1651341695560.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9788 size-full\" src=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-103228449_iOS-scaled-e1651341695560.jpg\" alt=\"\" width=\"1920\" height=\"2560\" srcset=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-103228449_iOS-scaled-e1651341695560.jpg 1920w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-103228449_iOS-scaled-e1651341695560-225x300.jpg 225w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-103228449_iOS-scaled-e1651341695560-768x1024.jpg 768w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-103228449_iOS-scaled-e1651341695560-1152x1536.jpg 1152w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-103228449_iOS-scaled-e1651341695560-1536x2048.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\"><\/a><\/p>\n<p>Ir a la Place de la Victoire para ver el <strong>Arsenal de Sainte Barbe<\/strong><\/p>\n<p><a href=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/IMG_1894-scaled-e1651053438543.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-7638 size-full\" src=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/IMG_1894-scaled-e1651053438543.jpg\" alt=\"\" width=\"1920\" height=\"2560\" srcset=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/IMG_1894-scaled-e1651053438543.jpg 1920w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/IMG_1894-scaled-e1651053438543-225x300.jpg 225w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/IMG_1894-scaled-e1651053438543-768x1024.jpg 768w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/IMG_1894-scaled-e1651053438543-1152x1536.jpg 1152w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/IMG_1894-scaled-e1651053438543-1536x2048.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\"><\/a><\/p>\n<p>Siga la <strong>rue des Chevaliers<\/strong> y vaya a la Iglesia de Sainte Foy.<\/p>\n<p>Iglesia de <strong>Sainte Foy<\/strong> : iglesia rom\u00e1nica del siglo XII. Tiene 3 torres y un magn\u00edfico p\u00f3rtico decorado.<\/p>\n<p><a href=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/DSC_2324-scaled-e1650908496308.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1797 size-full\" src=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/DSC_2324-scaled-e1650908496308.jpg\" alt=\"\" width=\"1702\" height=\"2560\" srcset=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/DSC_2324-scaled-e1650908496308.jpg 1702w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/DSC_2324-scaled-e1650908496308-199x300.jpg 199w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/DSC_2324-scaled-e1650908496308-681x1024.jpg 681w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/DSC_2324-scaled-e1650908496308-768x1155.jpg 768w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/DSC_2324-scaled-e1650908496308-1021x1536.jpg 1021w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/DSC_2324-scaled-e1650908496308-1362x2048.jpg 1362w\" sizes=\"(max-width: 1702px) 100vw, 1702px\"><\/a><\/p>\n<p><a href=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-125156477_iOS-scaled-e1651341482370.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9964 size-full\" src=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-125156477_iOS-scaled-e1651341482370.jpg\" alt=\"\" width=\"1920\" height=\"2560\" srcset=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-125156477_iOS-scaled-e1651341482370.jpg 1920w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-125156477_iOS-scaled-e1651341482370-225x300.jpg 225w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-125156477_iOS-scaled-e1651341482370-768x1024.jpg 768w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-125156477_iOS-scaled-e1651341482370-1152x1536.jpg 1152w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-125156477_iOS-scaled-e1651341482370-1536x2048.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\"><\/a><\/p>\n<p><strong>Eglise des R\u00e9collets<\/strong> : un vestigio del antiguo convento franciscano, su campanario data del siglo XV.<\/p>\n<p><a href=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/05\/Laterale-Residences-Selestat-132512806_iOS-scaled-e1651434021624.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-10140 size-full\" src=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/05\/Laterale-Residences-Selestat-132512806_iOS-scaled-e1651434021624.jpg\" alt=\"\" width=\"1920\" height=\"2560\" srcset=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/05\/Laterale-Residences-Selestat-132512806_iOS-scaled-e1651434021624.jpg 1920w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/05\/Laterale-Residences-Selestat-132512806_iOS-scaled-e1651434021624-225x300.jpg 225w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/05\/Laterale-Residences-Selestat-132512806_iOS-scaled-e1651434021624-768x1024.jpg 768w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/05\/Laterale-Residences-Selestat-132512806_iOS-scaled-e1651434021624-1152x1536.jpg 1152w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/05\/Laterale-Residences-Selestat-132512806_iOS-scaled-e1651434021624-1536x2048.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\"><\/a><\/p>\n<p><strong>La magia de S\u00e9lestat durante el Mercado de Navidad\u2026<\/strong><\/p>\n<p><a href=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/IMG_1309-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-7675 size-full\" src=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/IMG_1309-scaled.jpg\" alt=\"\" width=\"1920\" height=\"2560\" srcset=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/IMG_1309-scaled.jpg 1920w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/IMG_1309-225x300.jpg 225w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/IMG_1309-768x1024.jpg 768w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/IMG_1309-1152x1536.jpg 1152w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/IMG_1309-1536x2048.jpg 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\"><\/a><\/p>\n<h3>Un poco de gastronom\u00eda\u2026<\/h3>\n<p><strong>RESTAURANT LES LARMES DU VIN<\/strong><br>\n2, Place d\u2019Armes 67000 SELESTAT (domingo y lunes cerrado)<\/p>\n<p><a href=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-122800940_iOS-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9909 size-full\" src=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-122800940_iOS-scaled.jpg\" alt=\"Laterale Residences Selestat Larmes du Vin\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-122800940_iOS-scaled.jpg 2560w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-122800940_iOS-300x225.jpg 300w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-122800940_iOS-1024x768.jpg 1024w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-122800940_iOS-768x576.jpg 768w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-122800940_iOS-1536x1152.jpg 1536w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-122800940_iOS-2048x1536.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\"><\/a><\/p>\n<p><a href=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-105802718_iOS-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9887 size-full\" src=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-105802718_iOS-scaled.jpg\" alt=\"Laterale Residences Selestat Larmes du Vin\" width=\"2560\" height=\"1920\" srcset=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-105802718_iOS-scaled.jpg 2560w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-105802718_iOS-300x225.jpg 300w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-105802718_iOS-1024x768.jpg 1024w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-105802718_iOS-768x576.jpg 768w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-105802718_iOS-1536x1152.jpg 1536w, https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/Laterale-Residences-Selestat-105802718_iOS-2048x1536.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\"><\/a><\/p>\n<h3>Algunas direcciones para una dulce pausa\u2026<\/h3>\n<p><strong>P\u00c2TISSERIE SALON DE TH\u00c9 KAMM<\/strong><br>\n15, rue des Clefs \u2013 67600 \u2013 S\u00e9lestat \u2013 Francia<br>\n<strong>P\u00c2TISSERIE KOFFEL-SONNTAG<\/strong><br>\n2 y 10, rue du 17-Novembre \u2013 67600 \u2013 S\u00e9lestat \u2013 Francia<br>\n<strong>P\u00c2TISSERIE SALON DE TH\u00c9 BENOIT WACH<\/strong><br>\n7, rue des Chevaliers \u2013 67600 \u2013 S\u00e9lestat \u2013 Francia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuenta la leyenda que la ciudad fue fundada por el gigante Sletto. El primer registro escrito data del siglo VIII, pero el sitio era entonces parte del pueblo de Kintzheim. La expansi\u00f3n de la ciudad comenz\u00f3 en el siglo XI, cuando Hildegarde de Buren, madre del primero de los Hohenstaufen, fund\u00f3 all\u00ed una iglesia que fue ocupada a partir de 1094 por monjes de Conques, venerando a Sainte Foy.<br \/>\nEste priorato dirige la ciudad hasta que Federico II de Hohenstaufen otorga el estatus de ciudad libre a S\u00e9lestat. <\/p>\n","protected":false},"author":1,"featured_media":7636,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[81],"tags":[],"class_list":["post-6780","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-los-pueblos-mas-bonitos"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.7 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Selestat - Laterale Residences<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/laterale-residences.com\/es\/selestat\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Selestat\" \/>\n<meta property=\"og:description\" content=\"Cuenta la leyenda que la ciudad fue fundada por el gigante Sletto. El primer registro escrito data del siglo VIII, pero el sitio era entonces parte del pueblo de Kintzheim. La expansi\u00f3n de la ciudad comenz\u00f3 en el siglo XI, cuando Hildegarde de Buren, madre del primero de los Hohenstaufen, fund\u00f3 all\u00ed una iglesia que fue ocupada a partir de 1094 por monjes de Conques, venerando a Sainte Foy. Este priorato dirige la ciudad hasta que Federico II de Hohenstaufen otorga el estatus de ciudad libre a S\u00e9lestat.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/laterale-residences.com\/es\/selestat\/\" \/>\n<meta property=\"og:site_name\" content=\"Laterale Residences\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-25T06:26:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-01T07:15:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/IMG_1893-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"contact@laterale-residences.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"contact@laterale-residences.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/es\\\/selestat\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/es\\\/selestat\\\/\"},\"author\":{\"name\":\"contact@laterale-residences.com\",\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/es\\\/#\\\/schema\\\/person\\\/e059e7fbfe09a1de4a5070385ec9fce4\"},\"headline\":\"Selestat\",\"datePublished\":\"2022-04-25T06:26:42+00:00\",\"dateModified\":\"2022-07-01T07:15:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/es\\\/selestat\\\/\"},\"wordCount\":574,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/es\\\/selestat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/laterale-residences.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/IMG_1893-scaled.jpg\",\"articleSection\":[\"Los pueblos m\u00e1s bonitos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/laterale-residences.com\\\/es\\\/selestat\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/es\\\/selestat\\\/\",\"url\":\"https:\\\/\\\/laterale-residences.com\\\/es\\\/selestat\\\/\",\"name\":\"Selestat - Laterale Residences\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/es\\\/selestat\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/es\\\/selestat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/laterale-residences.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/IMG_1893-scaled.jpg\",\"datePublished\":\"2022-04-25T06:26:42+00:00\",\"dateModified\":\"2022-07-01T07:15:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/es\\\/selestat\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/laterale-residences.com\\\/es\\\/selestat\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/es\\\/selestat\\\/#primaryimage\",\"url\":\"https:\\\/\\\/laterale-residences.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/IMG_1893-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/laterale-residences.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/IMG_1893-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/es\\\/selestat\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/laterale-residences.com\\\/es\\\/bienvenida\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Selestat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/laterale-residences.com\\\/es\\\/\",\"name\":\"Laterale Residences\",\"description\":\"Appartements Vacances Riquewihr sur la route des vins d&#039;Alsace\",\"publisher\":{\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/laterale-residences.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/es\\\/#organization\",\"name\":\"Laterale Residences\",\"url\":\"https:\\\/\\\/laterale-residences.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/laterale-residences.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo_laterale_residences_etoiles.png\",\"contentUrl\":\"https:\\\/\\\/laterale-residences.com\\\/wp-content\\\/uploads\\\/2021\\\/07\\\/logo_laterale_residences_etoiles.png\",\"width\":600,\"height\":600,\"caption\":\"Laterale Residences\"},\"image\":{\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/laterale-residences.com\\\/es\\\/#\\\/schema\\\/person\\\/e059e7fbfe09a1de4a5070385ec9fce4\",\"name\":\"contact@laterale-residences.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2c6c46f89a7f510c694de34f653d75e6ce9a2782a83b3663358d125500655620?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2c6c46f89a7f510c694de34f653d75e6ce9a2782a83b3663358d125500655620?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2c6c46f89a7f510c694de34f653d75e6ce9a2782a83b3663358d125500655620?s=96&d=mm&r=g\",\"caption\":\"contact@laterale-residences.com\"},\"sameAs\":[\"https:\\\/\\\/laterale-residences.com\"],\"worksFor\":\"LATERALE RESIDENCES sarl\",\"url\":\"https:\\\/\\\/laterale-residences.com\\\/es\\\/author\\\/contactlaterale-residences-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Selestat - Laterale Residences","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/laterale-residences.com\/es\/selestat\/","og_locale":"es_ES","og_type":"article","og_title":"Selestat","og_description":"Cuenta la leyenda que la ciudad fue fundada por el gigante Sletto. El primer registro escrito data del siglo VIII, pero el sitio era entonces parte del pueblo de Kintzheim. La expansi\u00f3n de la ciudad comenz\u00f3 en el siglo XI, cuando Hildegarde de Buren, madre del primero de los Hohenstaufen, fund\u00f3 all\u00ed una iglesia que fue ocupada a partir de 1094 por monjes de Conques, venerando a Sainte Foy. Este priorato dirige la ciudad hasta que Federico II de Hohenstaufen otorga el estatus de ciudad libre a S\u00e9lestat.","og_url":"https:\/\/laterale-residences.com\/es\/selestat\/","og_site_name":"Laterale Residences","article_published_time":"2022-04-25T06:26:42+00:00","article_modified_time":"2022-07-01T07:15:50+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/IMG_1893-scaled.jpg","type":"image\/jpeg"}],"author":"contact@laterale-residences.com","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"contact@laterale-residences.com","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/laterale-residences.com\/es\/selestat\/#article","isPartOf":{"@id":"https:\/\/laterale-residences.com\/es\/selestat\/"},"author":{"name":"contact@laterale-residences.com","@id":"https:\/\/laterale-residences.com\/es\/#\/schema\/person\/e059e7fbfe09a1de4a5070385ec9fce4"},"headline":"Selestat","datePublished":"2022-04-25T06:26:42+00:00","dateModified":"2022-07-01T07:15:50+00:00","mainEntityOfPage":{"@id":"https:\/\/laterale-residences.com\/es\/selestat\/"},"wordCount":574,"commentCount":0,"publisher":{"@id":"https:\/\/laterale-residences.com\/es\/#organization"},"image":{"@id":"https:\/\/laterale-residences.com\/es\/selestat\/#primaryimage"},"thumbnailUrl":"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/IMG_1893-scaled.jpg","articleSection":["Los pueblos m\u00e1s bonitos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/laterale-residences.com\/es\/selestat\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/laterale-residences.com\/es\/selestat\/","url":"https:\/\/laterale-residences.com\/es\/selestat\/","name":"Selestat - Laterale Residences","isPartOf":{"@id":"https:\/\/laterale-residences.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/laterale-residences.com\/es\/selestat\/#primaryimage"},"image":{"@id":"https:\/\/laterale-residences.com\/es\/selestat\/#primaryimage"},"thumbnailUrl":"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/IMG_1893-scaled.jpg","datePublished":"2022-04-25T06:26:42+00:00","dateModified":"2022-07-01T07:15:50+00:00","breadcrumb":{"@id":"https:\/\/laterale-residences.com\/es\/selestat\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/laterale-residences.com\/es\/selestat\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/laterale-residences.com\/es\/selestat\/#primaryimage","url":"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/IMG_1893-scaled.jpg","contentUrl":"https:\/\/laterale-residences.com\/wp-content\/uploads\/2022\/04\/IMG_1893-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/laterale-residences.com\/es\/selestat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/laterale-residences.com\/es\/bienvenida\/"},{"@type":"ListItem","position":2,"name":"Selestat"}]},{"@type":"WebSite","@id":"https:\/\/laterale-residences.com\/es\/#website","url":"https:\/\/laterale-residences.com\/es\/","name":"Laterale Residences","description":"Appartements Vacances Riquewihr sur la route des vins d&#039;Alsace","publisher":{"@id":"https:\/\/laterale-residences.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/laterale-residences.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/laterale-residences.com\/es\/#organization","name":"Laterale Residences","url":"https:\/\/laterale-residences.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/laterale-residences.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/laterale-residences.com\/wp-content\/uploads\/2021\/07\/logo_laterale_residences_etoiles.png","contentUrl":"https:\/\/laterale-residences.com\/wp-content\/uploads\/2021\/07\/logo_laterale_residences_etoiles.png","width":600,"height":600,"caption":"Laterale Residences"},"image":{"@id":"https:\/\/laterale-residences.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/laterale-residences.com\/es\/#\/schema\/person\/e059e7fbfe09a1de4a5070385ec9fce4","name":"contact@laterale-residences.com","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2c6c46f89a7f510c694de34f653d75e6ce9a2782a83b3663358d125500655620?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2c6c46f89a7f510c694de34f653d75e6ce9a2782a83b3663358d125500655620?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2c6c46f89a7f510c694de34f653d75e6ce9a2782a83b3663358d125500655620?s=96&d=mm&r=g","caption":"contact@laterale-residences.com"},"sameAs":["https:\/\/laterale-residences.com"],"worksFor":"LATERALE RESIDENCES sarl","url":"https:\/\/laterale-residences.com\/es\/author\/contactlaterale-residences-com\/"}]}},"_links":{"self":[{"href":"https:\/\/laterale-residences.com\/es\/wp-json\/wp\/v2\/posts\/6780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/laterale-residences.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/laterale-residences.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/laterale-residences.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/laterale-residences.com\/es\/wp-json\/wp\/v2\/comments?post=6780"}],"version-history":[{"count":13,"href":"https:\/\/laterale-residences.com\/es\/wp-json\/wp\/v2\/posts\/6780\/revisions"}],"predecessor-version":[{"id":14813,"href":"https:\/\/laterale-residences.com\/es\/wp-json\/wp\/v2\/posts\/6780\/revisions\/14813"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/laterale-residences.com\/es\/wp-json\/wp\/v2\/media\/7636"}],"wp:attachment":[{"href":"https:\/\/laterale-residences.com\/es\/wp-json\/wp\/v2\/media?parent=6780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/laterale-residences.com\/es\/wp-json\/wp\/v2\/categories?post=6780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/laterale-residences.com\/es\/wp-json\/wp\/v2\/tags?post=6780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}